{"id":15423,"date":"2023-07-28T12:53:16","date_gmt":"2023-07-28T15:53:16","guid":{"rendered":"https:\/\/blog.alice.com.br\/?p=15423"},"modified":"2023-09-18T19:10:51","modified_gmt":"2023-09-18T22:10:51","slug":"o-que-e-osteoporose","status":"publish","type":"post","link":"https:\/\/alice.com.br\/blog\/sua-saude\/o-que-e-osteoporose\/","title":{"rendered":"O que \u00e9 osteoporose? Sintomas e tratamento"},"content":{"rendered":"<html><body><p>A gente pode at&eacute; achar que os ossos s&atilde;o estruturas maci&ccedil;as, mas a verdade &eacute; que h&aacute; v&aacute;rios espa&ccedil;os vazios dentro deles, que os tornam parecidos com colmeias. A compara&ccedil;&atilde;o ajuda a entender o que &eacute; a <strong>osteoporose<\/strong>, e como ela se manifesta no corpo.<\/p>\n<p>Assim como num favo de mel, os ossos t&ecirc;m pequenos buracos, o que &eacute; perfeitamente normal e natural. O que a osteoporose faz &eacute; aumentar o tamanho desses buracos, deixando o osso mais fr&aacute;gil e propenso a quebras.<\/p>\n<p>&Eacute; por isso que, na osteoporose, os ossos ficam fracos, finos e com uma densidade menor, o que aumenta a possibilidade das fraturas.<\/p><html><body><div class=\"cta cta--post--slim_withlogo\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alice.com.br\/\">\n\t\t\t\t\t\t\t\t\t<div class=\"logo\">\n\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/alice.com.br\/blog\/wp-content\/themes\/arada\/dist\/images\/alice.svg\" width=\"288\" height=\"150\" aria-label=\"hidden\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<span class=\"title\">Conhe&ccedil;a a Alice<\/span><span class=\"icon icon--arrow_right\"><\/span><\/a>\n\t\t\t\t\t\t\t\t<\/div><\/body><\/html>\n<h2>O que &eacute; osteoporose?<\/h2>\n<p>A palavra osteoporose vem do latim e significa &ldquo;ossos porosos&rdquo;.<\/p>\n<p>Para entender como tudo funciona, vale primeiro saber que os ossos s&atilde;o compostos por sais minerais, como pot&aacute;ssio, f&oacute;sforo e <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/alimentos-ricos-em-calcio\/\" target=\"_blank\" rel=\"noopener\">c&aacute;lcio<\/a>&nbsp;(inclusive, 99% do c&aacute;lcio que consumimos fica armazenado nos tecidos &oacute;sseos), al&eacute;m de outras subst&acirc;ncias, como o <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/colageno-para-que-serve\/\" target=\"_blank\" rel=\"noopener\">col&aacute;geno<\/a>.<\/p>\n<p>Esses elementos est&atilde;o presentes em um processo cont&iacute;nuo de quebra de tecido &oacute;sseo (que &eacute; reabsorvido) e de forma&ccedil;&atilde;o de um novo tecido &oacute;sseo (chamado de ossifica&ccedil;&atilde;o). E quem regula esse ciclo? V&aacute;rios horm&ocirc;nios e nutrientes.<\/p>\n<p>Se n&atilde;o tivermos n&iacute;veis adequados desses componentes, ou se fizermos uso de medicamentos que possam prejudicar a microarquitetura dos ossos, os espa&ccedil;os (ou poros) ficam maiores do que o esperado. E &eacute; a&iacute; que se identifica a osteoporose.<\/p>\n<p>&ldquo;O grande risco n&atilde;o &eacute; a osteoporose em si, mas eventuais quedas e fraturas facilitadas por essa fragilidade dos ossos. Quando a fratura ocorre, por exemplo, na coluna vertebral ou no quadril, a pessoa acaba tendo de ficar imobilizada, o que pode gerar outros danos em s&eacute;rie&rdquo;, explica Cintia Baule, m&eacute;dica de fam&iacute;lia e comunidade da <a href=\"https:\/\/alice.com.br\/blog\/\">Alice<\/a>.<\/p>\n<h2>O que pode causar a osteoporose?<\/h2>\n<p>V&aacute;rios fatores podem contribuir para o desenvolvimento da osteoporose. Entre os principais est&atilde;o as car&ecirc;ncias nutricionais, especialmente de c&aacute;lcio e de vitamina D.<\/p>\n<p>Isso porque a absor&ccedil;&atilde;o do c&aacute;lcio para composi&ccedil;&atilde;o dos ossos &eacute; estimulada pela vitamina D.<\/p>\n<p>Alimentos ricos em c&aacute;lcio s&atilde;o:<\/p>\n<ul>\n<li>Produtos <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/alimentos-ricos-em-calcio\/\">l&aacute;cteos<\/a>, como <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/tipos-de-leite\/\">leite,<\/a> queijo e <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/iogurte-natural-como-fazer\/\">iogurte;<\/a><\/li>\n<li>Vegetais de folhas verdes, como couve e br&oacute;colis;<\/li>\n<li>Peixes, como sardinha e salm&atilde;o.<\/li>\n<li>Gr&atilde;o de bico e feij&atilde;o branco.<\/li>\n<\/ul>\n<p>J&aacute; a melhor forma de obter <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/vitamina-d-para-que-serve-beneficios\/\">vitamina D<\/a> &eacute; tomando sol (<a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/o-que-bom-para-queimadura-de-sol\/\" target=\"_blank\" rel=\"noopener\">de forma saud&aacute;vel<\/a>) ou suplementando, quando necess&aacute;rio. Vale lembrar que a alimenta&ccedil;&atilde;o ajuda a alcan&ccedil;ar os n&iacute;veis adequados da vitamina.<\/p><html><body><div class=\"embed--webstorie\">\n\t\t\t\t\t\t\t<iframe src=\"https:\/\/alice.com.br\/blog\/?p=13862\" width=\"480\" height=\"568\"><\/iframe>\n\t\t\t\t\t\t<\/div><\/body><\/html>\n<h3>Altera&ccedil;&otilde;es hormonais<\/h3>\n<p>Altera&ccedil;&otilde;es hormonais tamb&eacute;m podem ter impacto no processo de ossifica&ccedil;&atilde;o. Inclusive, quando entram na <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/como-saber-se-estou-na-menopausa\/\">menopausa<\/a>, as pessoas ficam mais propensas a desenvolver a condi&ccedil;&atilde;o.<\/p>\n<p>&ldquo;A falta do estrog&ecirc;nio, ao fim do climat&eacute;rio, faz com que o osso passe a consumir mais a sua parte interna. Isso vai fazer com que a estrutura fique mais fraca&rdquo;, explica Baule.<\/p>\n<p>Tamb&eacute;m existem casos de osteoporose patol&oacute;gica, causada pela falha no funcionamento das gl&acirc;ndulas paratireoides, que ficam dentro da tireoide.<\/p>\n<p>Isso pode acontecer em pessoas jovens, mais comumente em decorr&ecirc;ncia de danos na regi&atilde;o, como tumor ou pela retirada das gl&acirc;ndulas. Nos dois casos, o comprometimento da produ&ccedil;&atilde;o hormonal tamb&eacute;m pode afetar o ciclo de forma&ccedil;&atilde;o dos tecidos &oacute;sseos.<\/p>\n<h3>Envelhecimento e perda de massa muscular<\/h3>\n<p>O avan&ccedil;ar da idade tamb&eacute;m est&aacute; associado ao aumento do risco de desenvolver a osteoporose.<\/p>\n<p>&ldquo;Com o envelhecimento, h&aacute; uma perda natural da capacidade de absor&ccedil;&atilde;o da vitamina D. Esta, por sua vez, atua na absor&ccedil;&atilde;o do c&aacute;lcio. H&aacute; tamb&eacute;m uma perda muscular&rdquo;, destaca a m&eacute;dica, que lembra: &ldquo;quando os m&uacute;sculos s&atilde;o exercitados, o osso &eacute; tamb&eacute;m estimulado a reabsorver c&aacute;lcio&rdquo;.<\/p>\n<p>A recomposi&ccedil;&atilde;o dos ossos tamb&eacute;m pode ser prejudicada por subst&acirc;ncias contidas em determinados medicamentos, pelo <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/como-parar-de-fumar-dicas\/\" target=\"_blank\" rel=\"noopener\">uso de cigarro<\/a> e pelo <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/vinho-faz-bem-mitos-verdades-bebidas-alcoolicas\/\" target=\"_blank\" rel=\"noopener\">consumo excessivo de &aacute;lcool<\/a>.<\/p>\n<h3>Fatores de risco para osteoporose<\/h3>\n<ul>\n<li>Defici&ecirc;ncias nutricionais;<\/li>\n<li>Baixo peso corporal;<\/li>\n<li>Altera&ccedil;&otilde;es hormonais;<\/li>\n<li>Hist&oacute;rico familiar;<\/li>\n<li>Idade avan&ccedil;ada;<\/li>\n<li>Uso de determinados medicamentos;<\/li>\n<li>Tabagismo;<\/li>\n<li>Consumo excessivo de &aacute;lcool.<\/li>\n<\/ul>\n<h2>Sintomas de osteoporose<\/h2>\n<p>Os sintomas da osteoporose n&atilde;o s&atilde;o muito evidentes e acabam sendo confundidos com outros problemas. Na verdade, muita gente s&oacute; descobre que desenvolveu o quadro quando sofre uma fratura.<\/p>\n<p>Por exemplo, a pessoa pode sentir dores em regi&otilde;es onde os ossos est&atilde;o localizados, mas associar a outras condi&ccedil;&otilde;es de sa&uacute;de. Quando sofre um trauma maior e faz os exames adequados, descobre que est&aacute; com osteoporose.<\/p>\n<p>H&aacute; pessoas que diminuem de tamanho com o tempo ou adquirem uma postura encurvada, conhecida como cifose, mas nem desconfiam de que est&atilde;o com a capacidade de forma&ccedil;&atilde;o &oacute;ssea comprometida.<\/p>\n<p>Essa perda de altura pode ocorrer devido a pequenas fraturas que fazem com que as v&eacute;rtebras se comprimam.<\/p>\n<h3>Osteoporose pode virar c&acirc;ncer?<\/h3>\n<p>N&atilde;o h&aacute; rela&ccedil;&atilde;o entre osteoporose e o desenvolvimento de c&acirc;ncer.<\/p>\n<p>Algumas pessoas fazem essa associa&ccedil;&atilde;o equivocadamente porque existe um tipo raro de c&acirc;ncer sangu&iacute;neo que surge na medula, chamado de mieloma m&uacute;ltiplo. Este causa dores e leva &agrave; deteriora&ccedil;&atilde;o dos ossos. Mas s&atilde;o condi&ccedil;&otilde;es de sa&uacute;de diferentes.<\/p>\n<h2>Como &eacute; feito o diagn&oacute;stico de osteoporose?<\/h2>\n<p>O diagn&oacute;stico de osteoporose leva em conta v&aacute;rios fatores, como estilo de vida, <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/historico-familiar-aliado-saude\/\" target=\"_blank\" rel=\"noopener\">hist&oacute;rico familiar<\/a>, queixas da pessoa e a ocorr&ecirc;ncia de traumas.<\/p>\n<p>Al&eacute;m disso, o profissional de sa&uacute;de pode indicar o exame de densitometria &oacute;ssea, que usa o raio-x para medir a quantidade de c&aacute;lcio e de outros minerais em uma parte espec&iacute;fica do osso.<\/p>\n<h2>Osteoporose tem cura?<\/h2>\n<p>N&atilde;o existe cura para a osteoporose, mas &eacute; poss&iacute;vel gerenciar os fatores que levam a essa condi&ccedil;&atilde;o e adotar medidas para prevenir as quedas.<\/p>\n<p>&ldquo;Tudo se resume a um estilo de vida saud&aacute;vel. Uma vida ativa pode gerar um envelhecimento saud&aacute;vel e diminuir o risco dos danos causados pela osteoporose&rdquo;, refor&ccedil;a Baule.<\/p>\n<h2>Tratamento e rem&eacute;dio para osteoporose<\/h2>\n<p>Alguns medicamentos podem ser usados para retardar a perda &oacute;ssea ou para ajudar a estimular o crescimento &oacute;sseo.<\/p>\n<p>Mas eles s&atilde;o apenas parte do tratamento, que tamb&eacute;m pode envolver a corre&ccedil;&atilde;o de car&ecirc;ncias nutricionais ou, quando necess&aacute;rio, uma terapia hormonal.<\/p>\n<p>A realiza&ccedil;&atilde;o de<a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/beneficios-atividade-fisica-dia-dia\/\" target=\"_blank\" rel=\"noopener\"> atividades f&iacute;sicas<\/a> &eacute; sempre fundamental. &ldquo;Prevenir queda envolve ter uma musculatura forte e trabalhar o equil&iacute;brio. Pesquisas indicam que o tai chi chuan, por exemplo, &eacute; muito ben&eacute;fico para a preven&ccedil;&atilde;o de quedas, mas tamb&eacute;m s&atilde;o recomendadas modalidades como <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/praticar-yoga-para-iniciantes\/\" target=\"_blank\" rel=\"noopener\">yoga<\/a>, <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/pilates-o-que-e-e-quais-sao-os-beneficios\/\" target=\"_blank\" rel=\"noopener\">pilates<\/a> e <a href=\"https:\/\/alice.com.br\/blog\/web-stories\/beneficios-da-musculacao\/\" target=\"_blank\" rel=\"noopener\">muscula&ccedil;&atilde;o<\/a>&ldquo;.<\/p>\n<p><a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/como-parar-de-fumar-dicas\/\" target=\"_blank\" rel=\"noopener\">Deixar de lado o cigarro<\/a> e as <a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/como-o-alcool-atrapalha-o-sono\/\" target=\"_blank\" rel=\"noopener\">bebidas alc&oacute;olicas<\/a> tamb&eacute;m faz parte do tratamento.<\/p>\n<h2>Como melhorar a sa&uacute;de dos ossos e prevenir a osteoporose?<\/h2>\n<ul>\n<li>Consuma c&aacute;lcio regularmente nas refei&ccedil;&otilde;es;<\/li>\n<li>Mantenha a vitamina D em n&iacute;veis adequados no organismo;<\/li>\n<li>Pratique exerc&iacute;cios de fortalecimento muscular;<\/li>\n<li>Fa&ccedil;a atividades que trabalhem o equil&iacute;brio corporal;<\/li>\n<li>Fique longe do cigarro;<\/li>\n<li>Evite consumir bebida alc&oacute;olica;<\/li>\n<li><a href=\"https:\/\/alice.com.br\/blog\/sua-saude\/dicas-para-dormir-melhor\/\" target=\"_blank\" rel=\"noopener\">Durma bem<\/a>.<\/li>\n<\/ul>\n<html><body><h2>Alice tem o plano de sa&uacute;de certo para a sua empresa!<\/h2>\n<p>Alice &eacute; uma empresa de tecnologia que oferece planos de sa&uacute;de empresarial e tem a miss&atilde;o de tornar o mundo mais saud&aacute;vel. Nossa plataforma de cuidado cont&iacute;nuo garante que os nossos membros recebam o cuidado certo, na hora certa e no lugar certo, proporcionando uma experi&ecirc;ncia excepcional para eles.<\/p>\n<p>Nossos planos t&ecirc;m cobertura nacional completa, assim como o atendimento e a experi&ecirc;ncia &uacute;nica do Alice Agora, parceiro de sa&uacute;de confi&aacute;vel para todas as horas, direto no app. Fale com o Time de Sa&uacute;de 24\/7, receba resposta em at&eacute; 60 segundos e, se precisar, j&aacute; fa&ccedil;a uma consulta virtual com nossa equipe m&eacute;dica.<\/p>\n<p>Alice tamb&eacute;m tem suporte completo ao seu RH, com dados estrat&eacute;gicos para sua gest&atilde;o &ndash; desde reports de sa&uacute;de populacional at&eacute; de custo de cuidado &ndash;, onboarding exclusivo e account manager dedicado.<\/p>\n<p>Veja como Alice cuida do seu time e do seu or&ccedil;amento.<\/p>\n<html><body><div class=\"cta cta--post--slim_withlogo\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alice.com.br\/simulador\">\n\t\t\t\t\t\t\t\t\t<div class=\"logo\">\n\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/alice.com.br\/blog\/wp-content\/themes\/arada\/dist\/images\/alice.svg\" width=\"288\" height=\"150\" aria-label=\"hidden\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<span class=\"title\">Fa&ccedil;a uma Cota&ccedil;&atilde;o<\/span><span class=\"icon icon--arrow_right\"><\/span><\/a>\n\t\t\t\t\t\t\t\t<\/div><\/body><\/html><\/body><\/html><\/body><\/html>\n","protected":false},"excerpt":{"rendered":"V\u00e1rios fatores podem causar a osteoporose, condi\u00e7\u00e3o marcada pela fragilidade dos ossos, que ficam mais propensos a fraturas. Saiba como prevenir. ","protected":false},"author":5,"featured_media":15424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[75,77,131],"class_list":["post-15423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sua-saude","tag-alimentacao","tag-exercicios-fisicos","tag-qualidade-de-vida"],"acf":[],"_links":{"self":[{"href":"https:\/\/alice.com.br\/blog\/wp-json\/wp\/v2\/posts\/15423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alice.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alice.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alice.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/alice.com.br\/blog\/wp-json\/wp\/v2\/comments?post=15423"}],"version-history":[{"count":3,"href":"https:\/\/alice.com.br\/blog\/wp-json\/wp\/v2\/posts\/15423\/revisions"}],"predecessor-version":[{"id":16043,"href":"https:\/\/alice.com.br\/blog\/wp-json\/wp\/v2\/posts\/15423\/revisions\/16043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alice.com.br\/blog\/wp-json\/wp\/v2\/media\/15424"}],"wp:attachment":[{"href":"https:\/\/alice.com.br\/blog\/wp-json\/wp\/v2\/media?parent=15423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alice.com.br\/blog\/wp-json\/wp\/v2\/categories?post=15423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alice.com.br\/blog\/wp-json\/wp\/v2\/tags?post=15423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}